{"id":561,"count":6,"description":"Diese Wagen sparen Bodenfl\u00e4che, verbessern die Betriebseffizienz und machen das Bewegen schwerer M\u00f6bel und Ger\u00e4te sicherer und einfacher. Stolz in den USA hergestellt, mit einer 12-j\u00e4hrigen Garantie, die unsere hochwertige Konstruktion best\u00e4tigt. Ob sie f\u00fcr gro\u00dfe Veranstaltungen, den t\u00e4glichen Betrieb oder als Lagerl\u00f6sung verwendet werden, XpressPort-Wagen rationalisieren den Prozess, verk\u00fcrzen die Auf- und Abbauzeiten und minimieren die k\u00f6rperliche Belastung Ihres Personals.","link":"https:\/\/mitylite.com\/de\/products\/carts\/xpressport","name":"Xpressport","slug":"xpressport","taxonomy":"product_cat","parent":132,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>XpressPort Chair &amp; Table Carts | MityLite<\/title>\n<meta name=\"description\" content=\"Need a reliable chair or table cart? XpressPort chair and table dollies are specially designed to make setup, cleanup, and storage a breeze. Shop yours today!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mitylite.com\/de\/products\/carts\/xpressport\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Xpressport Archives\" \/>\n<meta property=\"og:description\" content=\"Need a reliable chair or table cart? XpressPort chair and table dollies are specially designed to make setup, cleanup, and storage a breeze. Shop yours today!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mitylite.com\/de\/products\/carts\/xpressport\" \/>\n<meta property=\"og:site_name\" content=\"MityLite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/mitylite.com\\\/de\\\/products\\\/carts\\\/xpressport\",\"url\":\"https:\\\/\\\/mitylite.com\\\/de\\\/products\\\/carts\\\/xpressport\",\"name\":\"XpressPort Chair & Table Carts | MityLite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mitylite.com\\\/de\\\/#website\"},\"description\":\"Need a reliable chair or table cart? XpressPort chair and table dollies are specially designed to make setup, cleanup, and storage a breeze. Shop yours today!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mitylite.com\\\/de\\\/products\\\/carts\\\/xpressport#breadcrumb\"},\"inLanguage\":\"de-DE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mitylite.com\\\/de\\\/products\\\/carts\\\/xpressport#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mitylite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/mitylite.com\\\/products\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Carts\",\"item\":\"https:\\\/\\\/mitylite.com\\\/products\\\/carts\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Xpressport\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mitylite.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/mitylite.com\\\/de\\\/\",\"name\":\"MityLite\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mitylite.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"XpressPort Stuhl- und Tischwagen | MityLite","description":"Ben\u00f6tigen Sie einen zuverl\u00e4ssigen Stuhl- oder Tischwagen? Die Stuhl- und Tischwagen von XpressPort sind speziell daf\u00fcr konzipiert, Auf- und Abbau sowie Lagerung zum Kinderspiel zu machen. Kaufen Sie noch heute!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mitylite.com\/de\/products\/carts\/xpressport","og_locale":"de_DE","og_type":"article","og_title":"Xpressport Archives","og_description":"Need a reliable chair or table cart? XpressPort chair and table dollies are specially designed to make setup, cleanup, and storage a breeze. Shop yours today!","og_url":"https:\/\/mitylite.com\/de\/products\/carts\/xpressport","og_site_name":"MityLite","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mitylite.com\/de\/products\/carts\/xpressport","url":"https:\/\/mitylite.com\/de\/products\/carts\/xpressport","name":"XpressPort Stuhl- und Tischwagen | MityLite","isPartOf":{"@id":"https:\/\/mitylite.com\/de\/#website"},"description":"Ben\u00f6tigen Sie einen zuverl\u00e4ssigen Stuhl- oder Tischwagen? Die Stuhl- und Tischwagen von XpressPort sind speziell daf\u00fcr konzipiert, Auf- und Abbau sowie Lagerung zum Kinderspiel zu machen. Kaufen Sie noch heute!","breadcrumb":{"@id":"https:\/\/mitylite.com\/de\/products\/carts\/xpressport#breadcrumb"},"inLanguage":"de-DE"},{"@type":"BreadcrumbList","@id":"https:\/\/mitylite.com\/de\/products\/carts\/xpressport#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mitylite.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/mitylite.com\/products"},{"@type":"ListItem","position":3,"name":"Carts","item":"https:\/\/mitylite.com\/products\/carts"},{"@type":"ListItem","position":4,"name":"Xpressport"}]},{"@type":"WebSite","@id":"https:\/\/mitylite.com\/de\/#website","url":"https:\/\/mitylite.com\/de\/","name":"MityLite","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mitylite.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"}]}},"_links":{"self":[{"href":"https:\/\/mitylite.com\/de\/wp-json\/wp\/v2\/product_cat\/561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mitylite.com\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/mitylite.com\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/mitylite.com\/de\/wp-json\/wp\/v2\/product_cat\/132"}],"wp:post_type":[{"href":"https:\/\/mitylite.com\/de\/wp-json\/wp\/v2\/product?product_cat=561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}