{"id":26342,"date":"2023-03-28T09:15:43","date_gmt":"2023-03-28T15:15:43","guid":{"rendered":"https:\/\/mitylite.com\/?page_id=26342"},"modified":"2025-06-19T15:52:52","modified_gmt":"2025-06-19T21:52:52","slug":"greenguard-certified","status":"publish","type":"page","link":"https:\/\/mitylite.com\/de\/greenguard-certified","title":{"rendered":"Wir engagieren uns f\u00fcr die Schaffung ges\u00fcnderer Innenr\u00e4ume"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><a href=\"\/de\/greenguard-certified\/#headline1\">Was ist die GREENGUARD-Zertifizierung?<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"\/de\/greenguard-certified\/#headline2\">Okay, also was ist das Ausgasen?<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/mitylite.com\/de\/greenguard-certified\/#headline3\">Warum ist das Ausgasen potenziell sch\u00e4dlich?<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"\/de\/greenguard-certified\/#headline4\">Warum sollte ich einer GREENGUARD-Zertifizierung vertrauen?<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"\/de\/greenguard-certified\/#headline5\">Was bedeutet es dann, GREENGUARD-zertifiziert zu sein?<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"\/de\/greenguard-certified\/#headline6\">Wie wird ein Produkt GREENGUARD-zertifiziert?<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"\/de\/greenguard-certified\/#headline7\">Welche von MITY-Marken hergestellten Produkte sind GREENGUARD-zertifiziert?<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"headline1\">Was sind GREENGUARD-Zertifizierungen?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Einfach ausgedr\u00fcckt bietet das GREENGUARD-Zertifizierungsprogramm Herstellern wie MITY einen Standard, den sie befolgen m\u00fcssen, um bei den von unseren Marken hergestellten Produkten geringe chemische Emissionen oder \u201eAusgasungen\u201c zu erzielen, bevor unsere M\u00f6bel in Ihre H\u00e4user oder Unternehmen gelangen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"headline2\">Okay, also was ist Off-Gassing?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mit zunehmendem Alter k\u00f6nnen Materialien fl\u00fcchtige organische Verbindungen (VOCs) und andere Chemikalien ausgasen. Produkte, die Klebstoffe, Farben und Schaumstoffe enthalten, sind im Allgemeinen die h\u00f6chsten VOC-Emittenten. Der unverkennbare Geruch eines neuen Autos oder neuer Farbe und eines neuen Teppichs, wenn man einen Raum betritt \u2013 das sind Beispiele f\u00fcr VOCs und chemische Ausgasungen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"headline3\">Warum ist das Ausgasen potenziell sch\u00e4dlich?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Gute Frage. Wenn sich diese VOCs in Innenr\u00e4umen ansammeln, kann die Luft, die wir atmen, ungesund werden und manchmal Probleme wie Kopfschmerzen, \u00dcbelkeit, Schwindel oder vielleicht sogar noch schwerwiegendere Probleme wie Herz-Kreislauf-Erkrankungen, Fortpflanzungsst\u00f6rungen oder Krebs verursachen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"headline4\">Warum sollte ich einer GREENGUARD-Zertifizierung vertrauen?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Noch eine ausgezeichnete Frage! Erstens wird die GREENGUARD-Zertifizierung von Underwriters Laboratories (UL) Environment \u00fcberwacht. UL ist ein globales Sicherheitszertifizierungsunternehmen, das seit \u00fcber 120 Jahren besteht und eines von mehreren Unternehmen ist, die von der Occupational Safety and Health Administration (OSHA) f\u00fcr die Durchf\u00fchrung von Sicherheitstests zugelassen sind (Sie kennen wahrscheinlich die OSHA; sie ist die Bundesbeh\u00f6rde). Dadurch wird sichergestellt, dass Fabriken und Arbeitspl\u00e4tze in den USA f\u00fcr Arbeitnehmer sicher sind. UL unterst\u00fctzt Unternehmen dabei, die verantwortungsvolle Entwicklung und Produktion sichererer, nachhaltigerer und umweltfreundlicherer Produkte zu unterst\u00fctzen. Auf vielen Ihrer Elektroger\u00e4te und Produkte finden Sie das UL-Zertifizierungszeichen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es sieht aus wie das:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"479\" src=\"https:\/\/mitylite.com\/wp-content\/uploads\/2023\/03\/greenguard.png\" alt=\"Bild des Greenguard-Zertifizierungsabzeichens\" class=\"wp-image-26343\" style=\"width:200px;height:240px\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"headline5\">Was bedeutet es dann, GREENGUARD-zertifiziert zu sein?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Das GREENGUARD-Zertifizierungsprogramm von UL wird weltweit von Programmen und Bauvorschriften f\u00fcr nachhaltiges Bauen anerkannt. Die GREENGUARD-Zertifizierung bedeutet, dass ein Produkt wissenschaftlich erwiesenerma\u00dfen strenge Standards f\u00fcr chemische Emissionen erf\u00fcllt. Dadurch wird sichergestellt, dass ein Produkt oder Material nur geringe chemische Emissionen aufweist und die Qualit\u00e4t der Luft, in der es verwendet wird, verbessert.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"headline6\">Wie erh\u00e4lt ein Produkt die GREENGUARD-Zertifizierung?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Qualifikation f\u00fcr die GREENGUARD-Zertifizierung bedeutet, dass die von MITY-Marken hergestellten Produkte in eine dynamische Klimakammer mit sehr leistungsstarken chemischen Messsensoren gegeben werden, um zu sehen, wie viele VOCs sie an die Umwelt abgeben. (Es ist ganz Dexter&#039;s Laboratory.) Unsere Produkte werden auf \u00fcber 10.000 Chemikalien und Schadstoffe untersucht, um sicherzustellen, dass das, was Sie in Innenr\u00e4umen atmen, nicht durch die Belastung durch unsere Produkte beeintr\u00e4chtigt wird.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"headline7\">Welche von MITY-Marken hergestellten Produkte sind GREENGUARD-zertifiziert?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wir arbeiten weiterhin sehr hart daran, sicherzustellen, dass unsere Produkte GREENGUARD- oder GREENGUARD GOLD-zertifiziert sind.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mit Ausnahme unserer Madera-Tische ist auch unsere gesamte MityLite-Produktlinie GREENGUARD-zertifiziert.<\/li>\n\n\n\n<li>Alle MityLite-Tische, mit Ausnahme der Madera-Tische, sind GREENGUARD Gold-zertifiziert.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Wir freuen uns, diese Liste zu erweitern, da unsere Marken weiterhin Produkte f\u00fcr die GREENGUARD-Zertifizierung einreichen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Erfahren Sie mehr unter:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"http:\/\/greenguard.org\/en\/index.aspx\" target=\"_blank\" rel=\"noreferrer noopener\">greenguard.org<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.ul.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">UL.com<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>What is GREENGUARD Certification? Okay, so what\u2019s off-gassing? So, why is off-gassing potentially bad? Why should I trust a GREENGUARD Certification? So, what does being GREENGUARD Certified mean, then? How does a product get to be GREENGUARD Certified? What products manufactured by MITY brands are GREENGUARD certified? What is GREENGUARD Certifications? Simply put, the GREENGUARD [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-26342","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>We are Committed to Healthy Indoor Environments | MityLite<\/title>\n<meta name=\"description\" content=\"What is GREENGUARD Certification? Okay, so what\u2019s off-gassing? So, why is off-gassing potentially bad? Why should I trust a GREENGUARD Certification? So,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mitylite.com\/de\/greenguard-certified\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"We&#039;re Committed To Creating Healthier Indoor Environments\" \/>\n<meta property=\"og:description\" content=\"What is GREENGUARD Certification? Okay, so what\u2019s off-gassing? So, why is off-gassing potentially bad? Why should I trust a GREENGUARD Certification? So,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mitylite.com\/de\/greenguard-certified\" \/>\n<meta property=\"og:site_name\" content=\"MityLite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mitylite1\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-19T21:52:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mitylite.com\/wp-content\/uploads\/2023\/03\/greenguard.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mitylite.com\\\/de\\\/greenguard-certified\",\"url\":\"https:\\\/\\\/mitylite.com\\\/de\\\/greenguard-certified\",\"name\":\"We are Committed to Healthy Indoor Environments | MityLite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mitylite.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mitylite.com\\\/de\\\/greenguard-certified#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mitylite.com\\\/de\\\/greenguard-certified#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mitylite.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/greenguard.png\",\"datePublished\":\"2023-03-28T15:15:43+00:00\",\"dateModified\":\"2025-06-19T21:52:52+00:00\",\"description\":\"What is GREENGUARD Certification? Okay, so what\u2019s off-gassing? So, why is off-gassing potentially bad? Why should I trust a GREENGUARD Certification? So,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mitylite.com\\\/de\\\/greenguard-certified#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mitylite.com\\\/de\\\/greenguard-certified\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/mitylite.com\\\/de\\\/greenguard-certified#primaryimage\",\"url\":\"https:\\\/\\\/mitylite.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/greenguard.png\",\"contentUrl\":\"https:\\\/\\\/mitylite.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/greenguard.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mitylite.com\\\/de\\\/greenguard-certified#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mitylite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"We&#8217;re Committed To Creating Healthier Indoor Environments\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mitylite.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/mitylite.com\\\/de\\\/\",\"name\":\"MityLite\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mitylite.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Wir engagieren uns f\u00fcr ein gesundes Raumklima | MityLite","description":"Was ist die GREENGUARD-Zertifizierung? Okay, also was ist das Ausgasen? Warum ist das Ausgasen potenziell sch\u00e4dlich? Warum sollte ich einer GREENGUARD-Zertifizierung vertrauen? Also,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mitylite.com\/de\/greenguard-certified","og_locale":"de_DE","og_type":"article","og_title":"We're Committed To Creating Healthier Indoor Environments","og_description":"What is GREENGUARD Certification? Okay, so what\u2019s off-gassing? So, why is off-gassing potentially bad? Why should I trust a GREENGUARD Certification? So,","og_url":"https:\/\/mitylite.com\/de\/greenguard-certified","og_site_name":"MityLite","article_publisher":"https:\/\/www.facebook.com\/mitylite1\/","article_modified_time":"2025-06-19T21:52:52+00:00","og_image":[{"width":400,"height":479,"url":"https:\/\/mitylite.com\/wp-content\/uploads\/2023\/03\/greenguard.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mitylite.com\/de\/greenguard-certified","url":"https:\/\/mitylite.com\/de\/greenguard-certified","name":"Wir engagieren uns f\u00fcr ein gesundes Raumklima | MityLite","isPartOf":{"@id":"https:\/\/mitylite.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mitylite.com\/de\/greenguard-certified#primaryimage"},"image":{"@id":"https:\/\/mitylite.com\/de\/greenguard-certified#primaryimage"},"thumbnailUrl":"https:\/\/mitylite.com\/wp-content\/uploads\/2023\/03\/greenguard.png","datePublished":"2023-03-28T15:15:43+00:00","dateModified":"2025-06-19T21:52:52+00:00","description":"Was ist die GREENGUARD-Zertifizierung? Okay, also was ist das Ausgasen? Warum ist das Ausgasen potenziell sch\u00e4dlich? Warum sollte ich einer GREENGUARD-Zertifizierung vertrauen? Also,","breadcrumb":{"@id":"https:\/\/mitylite.com\/de\/greenguard-certified#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mitylite.com\/de\/greenguard-certified"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/mitylite.com\/de\/greenguard-certified#primaryimage","url":"https:\/\/mitylite.com\/wp-content\/uploads\/2023\/03\/greenguard.png","contentUrl":"https:\/\/mitylite.com\/wp-content\/uploads\/2023\/03\/greenguard.png"},{"@type":"BreadcrumbList","@id":"https:\/\/mitylite.com\/de\/greenguard-certified#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mitylite.com\/"},{"@type":"ListItem","position":2,"name":"We&#8217;re Committed To Creating Healthier Indoor Environments"}]},{"@type":"WebSite","@id":"https:\/\/mitylite.com\/de\/#website","url":"https:\/\/mitylite.com\/de\/","name":"MityLite","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mitylite.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"}]}},"_links":{"self":[{"href":"https:\/\/mitylite.com\/de\/wp-json\/wp\/v2\/pages\/26342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mitylite.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mitylite.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mitylite.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mitylite.com\/de\/wp-json\/wp\/v2\/comments?post=26342"}],"version-history":[{"count":3,"href":"https:\/\/mitylite.com\/de\/wp-json\/wp\/v2\/pages\/26342\/revisions"}],"predecessor-version":[{"id":38860,"href":"https:\/\/mitylite.com\/de\/wp-json\/wp\/v2\/pages\/26342\/revisions\/38860"}],"wp:attachment":[{"href":"https:\/\/mitylite.com\/de\/wp-json\/wp\/v2\/media?parent=26342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}